{"id":3,"count":1032,"description":"","link":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/","name":"BENER MERIAH","slug":"bener-meriah","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BENER MERIAH Arsip - MEDIA NASIONAL JURNALIS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BENER MERIAH Arsip - MEDIA NASIONAL JURNALIS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/\" \/>\n<meta property=\"og:site_name\" content=\"MEDIA NASIONAL JURNALIS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/index.php\\\/category\\\/bener-meriah\\\/\",\"url\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/index.php\\\/category\\\/bener-meriah\\\/\",\"name\":\"BENER MERIAH Arsip - MEDIA NASIONAL JURNALIS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/index.php\\\/category\\\/bener-meriah\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/index.php\\\/category\\\/bener-meriah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BENER MERIAH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/#website\",\"url\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/\",\"name\":\"MEDIA NASIONAL JURNALIS\",\"description\":\"Mengabarkan Berita Akurat Dan Terpercaya\",\"publisher\":{\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/#organization\",\"name\":\"MEDIA NASIONAL JURNALIS\",\"url\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-cropped-cropped-IMG-20260314-WA0049.jpg\",\"contentUrl\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-cropped-cropped-IMG-20260314-WA0049.jpg\",\"width\":1341,\"height\":328,\"caption\":\"MEDIA NASIONAL JURNALIS\"},\"image\":{\"@id\":\"https:\\\/\\\/medianasionaljurnalis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BENER MERIAH Arsip - MEDIA NASIONAL JURNALIS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/","og_locale":"id_ID","og_type":"article","og_title":"BENER MERIAH Arsip - MEDIA NASIONAL JURNALIS","og_url":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/","og_site_name":"MEDIA NASIONAL JURNALIS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/","url":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/","name":"BENER MERIAH Arsip - MEDIA NASIONAL JURNALIS","isPartOf":{"@id":"https:\/\/medianasionaljurnalis.com\/#website"},"breadcrumb":{"@id":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/medianasionaljurnalis.com\/index.php\/category\/bener-meriah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/medianasionaljurnalis.com\/"},{"@type":"ListItem","position":2,"name":"BENER MERIAH"}]},{"@type":"WebSite","@id":"https:\/\/medianasionaljurnalis.com\/#website","url":"https:\/\/medianasionaljurnalis.com\/","name":"MEDIA NASIONAL JURNALIS","description":"Mengabarkan Berita Akurat Dan Terpercaya","publisher":{"@id":"https:\/\/medianasionaljurnalis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medianasionaljurnalis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/medianasionaljurnalis.com\/#organization","name":"MEDIA NASIONAL JURNALIS","url":"https:\/\/medianasionaljurnalis.com\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/medianasionaljurnalis.com\/#\/schema\/logo\/image\/","url":"https:\/\/medianasionaljurnalis.com\/wp-content\/uploads\/2026\/03\/cropped-cropped-cropped-IMG-20260314-WA0049.jpg","contentUrl":"https:\/\/medianasionaljurnalis.com\/wp-content\/uploads\/2026\/03\/cropped-cropped-cropped-IMG-20260314-WA0049.jpg","width":1341,"height":328,"caption":"MEDIA NASIONAL JURNALIS"},"image":{"@id":"https:\/\/medianasionaljurnalis.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/medianasionaljurnalis.com\/index.php\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medianasionaljurnalis.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/medianasionaljurnalis.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/medianasionaljurnalis.com\/index.php\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}